{"id":76,"count":44,"description":"","link":"https:\/\/innovativerenal.com\/professional\/category\/news\/","name":"News","slug":"news","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v26.1.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>News Archives - Innovative Renal Care<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/innovativerenal.com\/professional\/category\/news\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/innovativerenal.com\/professional\/category\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"Innovative Renal Care\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/innovativerenal.com\/professional\/category\/news\/\",\"url\":\"https:\/\/innovativerenal.com\/professional\/category\/news\/\",\"name\":\"News Archives - Innovative Renal Care\",\"isPartOf\":{\"@id\":\"https:\/\/innovativerenal.com\/professional\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/innovativerenal.com\/professional\/category\/news\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/innovativerenal.com\/professional\/category\/news\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/innovativerenal.com\/professional\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/innovativerenal.com\/professional\/#website\",\"url\":\"https:\/\/innovativerenal.com\/professional\/\",\"name\":\"Innovative Renal Care\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/innovativerenal.com\/professional\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/innovativerenal.com\/professional\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/innovativerenal.com\/professional\/#organization\",\"name\":\"Innovative Renal Care\",\"url\":\"https:\/\/innovativerenal.com\/professional\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/innovativerenal.com\/professional\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/innovativerenal.com\/professional\/wp-content\/uploads\/sites\/3\/2024\/09\/IRC-location-placeholder-429.png-429.png\",\"contentUrl\":\"https:\/\/innovativerenal.com\/professional\/wp-content\/uploads\/sites\/3\/2024\/09\/IRC-location-placeholder-429.png-429.png\",\"width\":214,\"height\":237,\"caption\":\"Innovative Renal Care\"},\"image\":{\"@id\":\"https:\/\/innovativerenal.com\/professional\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/irchealth1\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"News Archives - Innovative Renal Care","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/innovativerenal.com\/professional\/category\/news\/","og_locale":"en_US","og_type":"article","og_title":"News Archives","og_url":"https:\/\/innovativerenal.com\/professional\/category\/news\/","og_site_name":"Innovative Renal Care","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/innovativerenal.com\/professional\/category\/news\/","url":"https:\/\/innovativerenal.com\/professional\/category\/news\/","name":"News Archives - Innovative Renal Care","isPartOf":{"@id":"https:\/\/innovativerenal.com\/professional\/#website"},"breadcrumb":{"@id":"https:\/\/innovativerenal.com\/professional\/category\/news\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/innovativerenal.com\/professional\/category\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/innovativerenal.com\/professional\/"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"https:\/\/innovativerenal.com\/professional\/#website","url":"https:\/\/innovativerenal.com\/professional\/","name":"Innovative Renal Care","description":"","publisher":{"@id":"https:\/\/innovativerenal.com\/professional\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/innovativerenal.com\/professional\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/innovativerenal.com\/professional\/#organization","name":"Innovative Renal Care","url":"https:\/\/innovativerenal.com\/professional\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/innovativerenal.com\/professional\/#\/schema\/logo\/image\/","url":"https:\/\/innovativerenal.com\/professional\/wp-content\/uploads\/sites\/3\/2024\/09\/IRC-location-placeholder-429.png-429.png","contentUrl":"https:\/\/innovativerenal.com\/professional\/wp-content\/uploads\/sites\/3\/2024\/09\/IRC-location-placeholder-429.png-429.png","width":214,"height":237,"caption":"Innovative Renal Care"},"image":{"@id":"https:\/\/innovativerenal.com\/professional\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/irchealth1"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/innovativerenal.com\/professional\/wp-json\/wp\/v2\/categories\/76","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/innovativerenal.com\/professional\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/innovativerenal.com\/professional\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/innovativerenal.com\/professional\/wp-json\/wp\/v2\/posts?categories=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}